{"id":18850,"date":"2023-09-11T12:03:25","date_gmt":"2023-09-11T12:03:25","guid":{"rendered":"https:\/\/taberg.de\/?p=18850"},"modified":"2023-09-11T12:03:28","modified_gmt":"2023-09-11T12:03:28","slug":"schlagader-der-energiewende-gleichstromverbindungen-a-nord","status":"publish","type":"post","link":"https:\/\/taberg.de\/en\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/","title":{"rendered":"The artery of the energy transition: Direct current connections A-North"},"content":{"rendered":"<p>By 2030, 65 percent of the electricity produced in Germany is to come from renewable energies. A large part of this energy is to be generated by wind power. For this purpose, powerful wind farms are being built, especially in the North Sea. The electricity generated here must be transported to where it is consumed, i.e. the wind farms must be connected to the transmission grid. Since the existing extra-high voltage connections are already at capacity and in some cases even overloaded, new transmission routes must be created. The A-North direct current link is an underground cable connection approximately 300 kilometres long, which can transmit a power of up to 2 gigawatts in the future.<\/p>\n\n\n\n<p>TABERG Ingenieure GmbH has already been working on geotechnical, environmental and soil ecology issues for the preparation of the planning approval documents for the 3 planning approval sections in Lower Saxony since 2018. <\/p>\n\n\n\n<p>Within the scope of the preliminary geotechnical investigation, existing documents and maps were evaluated and a geotechnical and environmental investigation concept was developed on this basis. For the implementation of the subsoil investigation, we took over the planning, tendering, construction supervision and expert monitoring of the work. Altogether, approx. 260 large boreholes and pressure soundings (approx. 5,000 drilling metres!) as well as approx. 2,800 borehole soundings and pile driving soundings (approx. 22,000 drilling metres!) were carried out. A special challenge was the exploration of the subsoil conditions below the Ems in the estuary area near Emden. For this purpose, drillings and pressure soundings were carried out to a depth of 40 m in the foreland of the dyke as well as with the help of floating drilling platforms on the water. Due to questions relevant to soil protection, numerous sites were also characterised by our soil experts (soil approach according to KA 5).<\/p>\n\n\n\n<p>Based on the available results and in close cooperation with other specialist planners as well as the developer (Amprion GmbH and Amprion Offshore GmbH), the documents for the submission of the planning approval (e.g. geotechnical report) were prepared.<\/p>\n\n\n\n<p>In addition to the construction-related aspects, there is also the question of ecological effects of the planned underground cable connection. In cooperation with the University of Trier and delta h Ingenieurgesellschaft mbH, a soil ecological assessment of the operational heat emissions was carried out on the basis of modelling using selected and representative guide profiles for the 300 km long route. The ecological assessment covered the effects on natural soil heat dynamics, soil water balance, nutrient balance as well as nitrogen dynamics and soil organic matter, vegetation and agriculture as well as on soil organisms and metabolic activities.<\/p>\n\n\n\n<p>In March 2023, the planning approval documents for the first two sections (approx. 107 km) were submitted to the responsible Federal Network Agency. Construction is scheduled to begin in 2024 and will take a total of approx. 3 years.<\/p>","protected":false},"excerpt":{"rendered":"<p>By 2030, 65 percent of the electricity produced in Germany is to be generated from renewable energies. A large part of this energy is to be<\/p>","protected":false},"author":3,"featured_media":18851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schlagader der Energiewende: Gleichstromverbindungen A-Nord - TABERG Ingenieure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taberg.de\/en\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schlagader der Energiewende: Gleichstromverbindungen A-Nord - TABERG Ingenieure\" \/>\n<meta property=\"og:description\" content=\"Bis 2030 soll 65 Prozent des in Deutschland produzierten Stroms aus erneuerbaren Energien gewonnen werden. Ein Gro\u00dfteil dieser Energie soll\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taberg.de\/en\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"TABERG Ingenieure\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-11T12:03:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T12:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taberg.de\/wp-content\/uploads\/2023\/09\/Image-A-Nord-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Norman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/\"},\"author\":{\"name\":\"Norman\",\"@id\":\"https:\\\/\\\/taberg.de\\\/#\\\/schema\\\/person\\\/01ce21a05c680c52062a61663145c529\"},\"headline\":\"Schlagader der Energiewende: Gleichstromverbindungen A-Nord\",\"datePublished\":\"2023-09-11T12:03:25+00:00\",\"dateModified\":\"2023-09-11T12:03:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/\"},\"wordCount\":401,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Image-A-Nord.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/\",\"url\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/\",\"name\":\"Schlagader der Energiewende: Gleichstromverbindungen A-Nord - TABERG Ingenieure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Image-A-Nord.jpg\",\"datePublished\":\"2023-09-11T12:03:25+00:00\",\"dateModified\":\"2023-09-11T12:03:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/#\\\/schema\\\/person\\\/01ce21a05c680c52062a61663145c529\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Image-A-Nord.jpg\",\"contentUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Image-A-Nord.jpg\",\"width\":4237,\"height\":2825},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taberg.de\\\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/taberg.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schlagader der Energiewende: Gleichstromverbindungen A-Nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\",\"url\":\"https:\\\/\\\/taberg.de\\\/\",\"name\":\"TABERG Ingenieure\",\"description\":\"Architekten und Ingenieure\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taberg.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/taberg.de\\\/#\\\/schema\\\/person\\\/01ce21a05c680c52062a61663145c529\",\"name\":\"Norman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55e7f78568fc7d80865c5146bea0e599309c71678b84490c4bd8450082458d6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55e7f78568fc7d80865c5146bea0e599309c71678b84490c4bd8450082458d6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55e7f78568fc7d80865c5146bea0e599309c71678b84490c4bd8450082458d6b?s=96&d=mm&r=g\",\"caption\":\"Norman\"},\"url\":\"https:\\\/\\\/taberg.de\\\/en\\\/author\\\/norman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schlagader der Energiewende: Gleichstromverbindungen A-Nord - TABERG Ingenieure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taberg.de\/en\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/","og_locale":"en_GB","og_type":"article","og_title":"Schlagader der Energiewende: Gleichstromverbindungen A-Nord - TABERG Ingenieure","og_description":"Bis 2030 soll 65 Prozent des in Deutschland produzierten Stroms aus erneuerbaren Energien gewonnen werden. Ein Gro\u00dfteil dieser Energie soll","og_url":"https:\/\/taberg.de\/en\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/","og_site_name":"TABERG Ingenieure","article_published_time":"2023-09-11T12:03:25+00:00","article_modified_time":"2023-09-11T12:03:28+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/taberg.de\/wp-content\/uploads\/2023\/09\/Image-A-Nord-1024x683.jpg","type":"image\/jpeg"}],"author":"Norman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Norman","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#article","isPartOf":{"@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/"},"author":{"name":"Norman","@id":"https:\/\/taberg.de\/#\/schema\/person\/01ce21a05c680c52062a61663145c529"},"headline":"Schlagader der Energiewende: Gleichstromverbindungen A-Nord","datePublished":"2023-09-11T12:03:25+00:00","dateModified":"2023-09-11T12:03:28+00:00","mainEntityOfPage":{"@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/"},"wordCount":401,"commentCount":0,"image":{"@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2023\/09\/Image-A-Nord.jpg","articleSection":["Uncategorized"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/","url":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/","name":"Schlagader der Energiewende: Gleichstromverbindungen A-Nord - TABERG Ingenieure","isPartOf":{"@id":"https:\/\/taberg.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#primaryimage"},"image":{"@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2023\/09\/Image-A-Nord.jpg","datePublished":"2023-09-11T12:03:25+00:00","dateModified":"2023-09-11T12:03:28+00:00","author":{"@id":"https:\/\/taberg.de\/#\/schema\/person\/01ce21a05c680c52062a61663145c529"},"breadcrumb":{"@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#primaryimage","url":"https:\/\/taberg.de\/wp-content\/uploads\/2023\/09\/Image-A-Nord.jpg","contentUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2023\/09\/Image-A-Nord.jpg","width":4237,"height":2825},{"@type":"BreadcrumbList","@id":"https:\/\/taberg.de\/schlagader-der-energiewende-gleichstromverbindungen-a-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taberg.de\/"},{"@type":"ListItem","position":2,"name":"Schlagader der Energiewende: Gleichstromverbindungen A-Nord"}]},{"@type":"WebSite","@id":"https:\/\/taberg.de\/#website","url":"https:\/\/taberg.de\/","name":"TABERG Location","description":"Architects and engineers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taberg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/taberg.de\/#\/schema\/person\/01ce21a05c680c52062a61663145c529","name":"Norman","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/55e7f78568fc7d80865c5146bea0e599309c71678b84490c4bd8450082458d6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55e7f78568fc7d80865c5146bea0e599309c71678b84490c4bd8450082458d6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55e7f78568fc7d80865c5146bea0e599309c71678b84490c4bd8450082458d6b?s=96&d=mm&r=g","caption":"Norman"},"url":"https:\/\/taberg.de\/en\/author\/norman\/"}]}},"_links":{"self":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/posts\/18850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/comments?post=18850"}],"version-history":[{"count":1,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/posts\/18850\/revisions"}],"predecessor-version":[{"id":18852,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/posts\/18850\/revisions\/18852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media\/18851"}],"wp:attachment":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media?parent=18850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/categories?post=18850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/tags?post=18850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}