{"id":16204,"date":"2022-08-04T11:37:42","date_gmt":"2022-08-04T11:37:42","guid":{"rendered":"https:\/\/taberg.de\/?post_type=product&#038;p=16204"},"modified":"2022-08-30T13:31:23","modified_gmt":"2022-08-30T13:31:23","slug":"bv-ruckbau-markisches-zentrum-berlin","status":"publish","type":"product","link":"https:\/\/taberg.de\/en\/product\/bv-ruckbau-markisches-zentrum-berlin\/","title":{"rendered":"BV Deconstruction M\u00e4rkisches Zentrum Berlin"},"content":{"rendered":"<ul>\n<li>Additional pollutant investigations, expert monitoring of pollutant remediation,<br \/>\nGutting, deconstruction, excavation<\/li>\n<li>2020 - probably summer 2022<\/li>\n<li>Client: Full-service real estate manager<\/li>\n<li>Conducted by M&amp;P D\u00fcsseldorf with M&amp;P Berlin<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Additional pollutant investigations, expert support Pollutant remediation, gutting, demolition, excavation 2020 - probably summer 2022 Client: Full-service property manager Carried out by M&amp;P<\/p>","protected":false},"featured_media":16234,"template":"","meta":[],"product_brand":[],"product_cat":[37],"product_tag":[],"class_list":{"0":"post-16204","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bau","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin - TABERG Ingenieure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taberg.de\/en\/product\/bv-ruckbau-markisches-zentrum-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin - TABERG Ingenieure\" \/>\n<meta property=\"og:description\" content=\"Zus\u00e4tzliche Schadstoffuntersuchungen, gutachterliche Begleitung Schadstoffsanierung, Entkernung, R\u00fcckbau, Erdaushub 2020 \u2013 voraussichtlich Sommer 2022 Auftraggeber: Full-Service Immobilien Manager Durchgef\u00fchrt durch M&amp;P\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taberg.de\/en\/product\/bv-ruckbau-markisches-zentrum-berlin\/\" \/>\n<meta property=\"og:site_name\" content=\"TABERG Ingenieure\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-30T13:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/Picture1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1017\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/\",\"url\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/\",\"name\":\"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin - TABERG Ingenieure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Picture1.jpg\",\"datePublished\":\"2022-08-04T11:37:42+00:00\",\"dateModified\":\"2022-08-30T13:31:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Picture1.jpg\",\"contentUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Picture1.jpg\",\"width\":1017,\"height\":763},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/bv-ruckbau-markisches-zentrum-berlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/taberg.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLE PROJEKTE\",\"item\":\"https:\\\/\\\/taberg.de\\\/alle-projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\",\"url\":\"https:\\\/\\\/taberg.de\\\/\",\"name\":\"TABERG Ingenieure\",\"description\":\"Architekten und Ingenieure\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taberg.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin - TABERG Ingenieure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taberg.de\/en\/product\/bv-ruckbau-markisches-zentrum-berlin\/","og_locale":"en_GB","og_type":"article","og_title":"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin - TABERG Ingenieure","og_description":"Zus\u00e4tzliche Schadstoffuntersuchungen, gutachterliche Begleitung Schadstoffsanierung, Entkernung, R\u00fcckbau, Erdaushub 2020 \u2013 voraussichtlich Sommer 2022 Auftraggeber: Full-Service Immobilien Manager Durchgef\u00fchrt durch M&amp;P","og_url":"https:\/\/taberg.de\/en\/product\/bv-ruckbau-markisches-zentrum-berlin\/","og_site_name":"TABERG Ingenieure","article_modified_time":"2022-08-30T13:31:23+00:00","og_image":[{"width":1017,"height":763,"url":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/Picture1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/","url":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/","name":"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin - TABERG Ingenieure","isPartOf":{"@id":"https:\/\/taberg.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/#primaryimage"},"image":{"@id":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/Picture1.jpg","datePublished":"2022-08-04T11:37:42+00:00","dateModified":"2022-08-30T13:31:23+00:00","breadcrumb":{"@id":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/#primaryimage","url":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/Picture1.jpg","contentUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/Picture1.jpg","width":1017,"height":763},{"@type":"BreadcrumbList","@id":"https:\/\/taberg.de\/product\/bv-ruckbau-markisches-zentrum-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taberg.de\/"},{"@type":"ListItem","position":2,"name":"ALLE PROJEKTE","item":"https:\/\/taberg.de\/alle-projekte\/"},{"@type":"ListItem","position":3,"name":"BV R\u00fcckbau M\u00e4rkisches Zentrum Berlin"}]},{"@type":"WebSite","@id":"https:\/\/taberg.de\/#website","url":"https:\/\/taberg.de\/","name":"TABERG Location","description":"Architects and engineers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taberg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16204\/revisions"}],"predecessor-version":[{"id":17101,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16204\/revisions\/17101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media\/16234"}],"wp:attachment":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media?parent=16204"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_brand?post=16204"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_cat?post=16204"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_tag?post=16204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}