{"id":16217,"date":"2022-08-04T11:37:45","date_gmt":"2022-08-04T11:37:45","guid":{"rendered":"https:\/\/taberg.de\/?post_type=product&#038;p=16217"},"modified":"2022-08-30T13:29:01","modified_gmt":"2022-08-30T13:29:01","slug":"deponieschliesung-ehem-deponie-colonia-und-neubebauung","status":"publish","type":"product","link":"https:\/\/taberg.de\/en\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/","title":{"rendered":"Closure of the former Colonia landfill and new development"},"content":{"rendered":"<ul>\n<li>Services: Planning of the sealing, application according to \u00a735 KrWG, tendering, construction management, aftercare<\/li>\n<li>Duration: 2015 - 2020 Planning and construction period, since 2020 Aftercare<\/li>\n<li>Industry of the client: Real estate<\/li>\n<li>Superstructure with trade<\/li>\n<li>Environmental assessments of M&amp;P Hannover<\/li>\n<li>Shallow foundations on former building rubble landfill part<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Services: Planning of the sealing, application according to \u00a735 KrWG, tendering, construction management, aftercare Term: 2015 - 2020 Planning and construction period, since 2020<\/p>","protected":false},"featured_media":16265,"template":"","meta":[],"product_brand":[],"product_cat":[39],"product_tag":[],"class_list":{"0":"post-16217","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-geotechnik","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung - TABERG Ingenieure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taberg.de\/en\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung - TABERG Ingenieure\" \/>\n<meta property=\"og:description\" content=\"Leistungen: Planung der Abdichtung, Antragsstellung nach \u00a735 KrWG, Ausschreibung, Bauleitung, Nachsorge Laufzeit: 2015 \u2013 2020 Planung und Bauzeit, seit 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taberg.de\/en\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/\" \/>\n<meta property=\"og:site_name\" content=\"TABERG Ingenieure\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-30T13:29:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/\",\"url\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/\",\"name\":\"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung - TABERG Ingenieure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/a-1.jpg\",\"datePublished\":\"2022-08-04T11:37:45+00:00\",\"dateModified\":\"2022-08-30T13:29:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/a-1.jpg\",\"contentUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/a-1.jpg\",\"width\":586,\"height\":439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/taberg.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLE PROJEKTE\",\"item\":\"https:\\\/\\\/taberg.de\\\/alle-projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\",\"url\":\"https:\\\/\\\/taberg.de\\\/\",\"name\":\"TABERG Ingenieure\",\"description\":\"Architekten und Ingenieure\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taberg.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung - TABERG Ingenieure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taberg.de\/en\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/","og_locale":"en_GB","og_type":"article","og_title":"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung - TABERG Ingenieure","og_description":"Leistungen: Planung der Abdichtung, Antragsstellung nach \u00a735 KrWG, Ausschreibung, Bauleitung, Nachsorge Laufzeit: 2015 \u2013 2020 Planung und Bauzeit, seit 2020","og_url":"https:\/\/taberg.de\/en\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/","og_site_name":"TABERG Ingenieure","article_modified_time":"2022-08-30T13:29:01+00:00","og_image":[{"width":586,"height":439,"url":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/","url":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/","name":"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung - TABERG Ingenieure","isPartOf":{"@id":"https:\/\/taberg.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/#primaryimage"},"image":{"@id":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/#primaryimage"},"thumbnailUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-1.jpg","datePublished":"2022-08-04T11:37:45+00:00","dateModified":"2022-08-30T13:29:01+00:00","breadcrumb":{"@id":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/#primaryimage","url":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-1.jpg","contentUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-1.jpg","width":586,"height":439},{"@type":"BreadcrumbList","@id":"https:\/\/taberg.de\/product\/deponieschliesung-ehem-deponie-colonia-und-neubebauung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taberg.de\/"},{"@type":"ListItem","position":2,"name":"ALLE PROJEKTE","item":"https:\/\/taberg.de\/alle-projekte\/"},{"@type":"ListItem","position":3,"name":"Deponieschlie\u00dfung ehem. Deponie Colonia und Neubebauung"}]},{"@type":"WebSite","@id":"https:\/\/taberg.de\/#website","url":"https:\/\/taberg.de\/","name":"TABERG Location","description":"Architects and engineers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taberg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16217\/revisions"}],"predecessor-version":[{"id":17099,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16217\/revisions\/17099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media\/16265"}],"wp:attachment":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media?parent=16217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_brand?post=16217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_cat?post=16217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_tag?post=16217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}