{"id":16232,"date":"2022-08-04T11:37:49","date_gmt":"2022-08-04T11:37:49","guid":{"rendered":"https:\/\/taberg.de\/?post_type=product&#038;p=16232"},"modified":"2022-08-30T13:20:13","modified_gmt":"2022-08-30T13:20:13","slug":"errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg","status":"publish","type":"product","link":"https:\/\/taberg.de\/en\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/","title":{"rendered":"Construction of a multifunctional sealing system at the Ihlenberg landfill site"},"content":{"rendered":"<ul>\n<li>Project description: A planning approval procedure had to be carried out for the construction of a multifunctional sealing (MFA) as an intermediate sealing between two landfill sections.<\/li>\n<li>Our services: Deficit analysis of the available planning documents, implementation of the environmental impact assessment with preparation of a scoping document, attendance of the scoping meeting to coordinate the scope of the assessment with the approval authority, coordination of expert consultants as subcontractors, preparation of the report on the environmental impact assessment.<\/li>\n<li>Duration: 2019 - 2022<\/li>\n<li>Industry of the client: Waste disposal company \/ landfill operator<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Project description: A planning approval procedure had to be carried out for the construction of a multifunctional sealing (MFA) as an intermediate sealing between two landfill sections. Our services: Deficit analysis<\/p>","protected":false},"featured_media":16275,"template":"","meta":[],"product_brand":[],"product_cat":[40],"product_tag":[],"class_list":{"0":"post-16232","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-umwelt","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg - TABERG Ingenieure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taberg.de\/en\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg - TABERG Ingenieure\" \/>\n<meta property=\"og:description\" content=\"Projektbeschreibung: F\u00fcr die Errichtung einer Multifunktionalen Abdichtung (MFA) als Zwischenabdichtung zwischen zwei Deponieabschnitten war ein Planfeststellungsverfahren durchzuf\u00fchren. Unsere Leistungen: Defizitanalyse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taberg.de\/en\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/\" \/>\n<meta property=\"og:site_name\" content=\"TABERG Ingenieure\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-30T13:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/\",\"url\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/\",\"name\":\"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg - TABERG Ingenieure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/a-7.jpg\",\"datePublished\":\"2022-08-04T11:37:49+00:00\",\"dateModified\":\"2022-08-30T13:20:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/a-7.jpg\",\"contentUrl\":\"https:\\\/\\\/taberg.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/a-7.jpg\",\"width\":586,\"height\":439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taberg.de\\\/product\\\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/taberg.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLE PROJEKTE\",\"item\":\"https:\\\/\\\/taberg.de\\\/alle-projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taberg.de\\\/#website\",\"url\":\"https:\\\/\\\/taberg.de\\\/\",\"name\":\"TABERG Ingenieure\",\"description\":\"Architekten und Ingenieure\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taberg.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg - TABERG Ingenieure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taberg.de\/en\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/","og_locale":"en_GB","og_type":"article","og_title":"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg - TABERG Ingenieure","og_description":"Projektbeschreibung: F\u00fcr die Errichtung einer Multifunktionalen Abdichtung (MFA) als Zwischenabdichtung zwischen zwei Deponieabschnitten war ein Planfeststellungsverfahren durchzuf\u00fchren. Unsere Leistungen: Defizitanalyse","og_url":"https:\/\/taberg.de\/en\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/","og_site_name":"TABERG Ingenieure","article_modified_time":"2022-08-30T13:20:13+00:00","og_image":[{"width":586,"height":439,"url":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/","url":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/","name":"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg - TABERG Ingenieure","isPartOf":{"@id":"https:\/\/taberg.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/#primaryimage"},"image":{"@id":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/#primaryimage"},"thumbnailUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-7.jpg","datePublished":"2022-08-04T11:37:49+00:00","dateModified":"2022-08-30T13:20:13+00:00","breadcrumb":{"@id":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/#primaryimage","url":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-7.jpg","contentUrl":"https:\/\/taberg.de\/wp-content\/uploads\/2022\/08\/a-7.jpg","width":586,"height":439},{"@type":"BreadcrumbList","@id":"https:\/\/taberg.de\/product\/errichtung-einer-multifunktionalen-abdichtung-auf-der-deponie-ihlenberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taberg.de\/"},{"@type":"ListItem","position":2,"name":"ALLE PROJEKTE","item":"https:\/\/taberg.de\/alle-projekte\/"},{"@type":"ListItem","position":3,"name":"Errichtung einer Multifunktionalen Abdichtung auf der Deponie Ihlenberg"}]},{"@type":"WebSite","@id":"https:\/\/taberg.de\/#website","url":"https:\/\/taberg.de\/","name":"TABERG Location","description":"Architects and engineers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taberg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16232\/revisions"}],"predecessor-version":[{"id":17083,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product\/16232\/revisions\/17083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media\/16275"}],"wp:attachment":[{"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/media?parent=16232"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_brand?post=16232"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_cat?post=16232"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/taberg.de\/en\/wp-json\/wp\/v2\/product_tag?post=16232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}